{"id":1220,"date":"2026-05-13T08:27:59","date_gmt":"2026-05-13T08:27:59","guid":{"rendered":"https:\/\/www.teamone.be\/jobs\/electromecanicien-h-f-x-2\/"},"modified":"2026-05-13T08:27:59","modified_gmt":"2026-05-13T08:27:59","slug":"electromecanicien-h-f-x-2","status":"publish","type":"job","link":"https:\/\/www.teamone.be\/nl\/jobs\/electromecanicien-h-f-x-2\/","title":{"rendered":"Electrom\u00e9canicien (H\/F\/X)"},"content":{"rendered":"<p>Notre agence TeamOne de Huy est \u00e0 la recherche pour l&#8217;un de ses clients recherche un \u00e9lectrom\u00e9canicien pour son site d&#8217;exploitation d&#8217;Engis<\/p>\n<p>&#8211; Vous aurez en charge le d\u00e9pannage des lignes de production du site (industrie chimique).<br \/>\n&#8211; Vous vous occuperez de la r\u00e9solution des probl\u00e8mes techniques et de leur am\u00e9lioration (maintenance pr\u00e9ventive) en m\u00e9canique, \u00e9lectricit\u00e9 et pneumatique.<br \/>\n&#8211; Vous r\u00e9aliserez vos diff\u00e9rentes t\u00e2ches en respectant les proc\u00e9dures et les consignes tr\u00e8s strictes en mati\u00e8re de s\u00e9curit\u00e9.<br \/>\n&#8211; Vous rapporterez au contrema\u00eetre technique du site en collaboration avec le service production.<\/p>\n<p>Notre offre:<\/p>\n<p>&#8211; CDI<br \/>\n&#8211; R\u00e9gime de travail : Temps plein 2 pauses<br \/>\n&#8211; Heures\/sem: 39h00<br \/>\n&#8211; Horaire : 2 pauses : 6h-14h et 14h-22h<br \/>\n&#8211; Salaire : CP 116 secteur chimie<br \/>\n&#8211; Avantages : Ch\u00e8que-repas 10\u20ac<\/p>\n<p>Int\u00e9ress\u00e9 par cette offre? Transmettez sans attendre votre candidature par mail \u00e0 cvhuy@teamone.be ou postulez directement en ligne!<\/p>\n<p>#TeamHuy<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notre agence TeamOne de Huy est \u00e0 la recherche pour l&#8217;un de ses clients recherche un \u00e9lectrom\u00e9canicien pour son site d&#8217;exploitation d&#8217;Engis<\/p>\n","protected":false},"template":"","job_sector":[25],"job_function":[87],"job_branch":[172],"job_province":[159],"job_city":[197],"class_list":["post-1220","job","type-job","status-publish","hentry","job_sector-industrie-autres","job_function-electricite","job_branch-team-one-huy","job_province-liege","job_city-engis"],"acf":{"external_id":"9256","reference":"","city":"Engis","zip":"4480","duration":"Temps plein en CDI","required_years_of_experience":1,"language":"Frans","sector_text":"Industrie (autres)","intro":"Notre agence TeamOne de Huy est \u00e0 la recherche pour l'un de ses clients recherche un \u00e9lectrom\u00e9canicien pour son site d'exploitation d'Engis","task_and_profile":"- Vous aurez en charge le d\u00e9pannage des lignes de production du site (industrie chimique).\n- Vous vous occuperez de la r\u00e9solution des probl\u00e8mes techniques et de leur am\u00e9lioration (maintenance pr\u00e9ventive) en m\u00e9canique, \u00e9lectricit\u00e9 et pneumatique.\n- Vous r\u00e9aliserez vos diff\u00e9rentes t\u00e2ches en respectant les proc\u00e9dures et les consignes tr\u00e8s strictes en mati\u00e8re de s\u00e9curit\u00e9.\n- Vous rapporterez au contrema\u00eetre technique du site en collaboration avec le service production.","offer":"Notre offre:\n\n- CDI \n- R\u00e9gime de travail : Temps plein 2 pauses\n- Heures\/sem: 39h00\n- Horaire : 2 pauses : 6h-14h et 14h-22h \n- Salaire : CP 116 secteur chimie\n- Avantages : Ch\u00e8que-repas 10\u20ac\n\nInt\u00e9ress\u00e9 par cette offre? Transmettez sans attendre votre candidature par mail \u00e0 cvhuy@teamone.be ou postulez directement en ligne!\n\n\n#TeamHuy","skills":"Bachelier en m\u00e9canique, \u00e9lectrom\u00e9canique, \u00e9lectricit\u00e9 ou exp\u00e9rience \u00e9quivalente\n\nVous \u00eates flexible et pr\u00eat \u00e0 travailler en pauses\n\nVous disposez de bonnes capacit\u00e9s d\u2019analyse et de raisonnement\n\nVous savez organiser votre travail et faites preuve d\u2019initiative\n\nVous ma\u00eetrisez l\u2019outil informatique, notamment la GMAO (Gestion de la Maintenance Assist\u00e9e par Ordinateur)\n\nVous \u00eates une personne de terrain, dot\u00e9e d\u2019un bon esprit d\u2019\u00e9quipe\n\nVous faites preuve de proactivit\u00e9 et d\u2019esprit critique","client_name":"REVATECH","publication_start":"2026-05-11","publication_end":"2026-05-31"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Electrom\u00e9canicien (H\/F\/X) - TeamOne<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.teamone.be\/nl\/jobs\/electromecanicien-h-f-x-2\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Electrom\u00e9canicien (H\/F\/X) - TeamOne\" \/>\n<meta property=\"og:description\" content=\"Notre agence TeamOne de Huy est \u00e0 la recherche pour l&#039;un de ses clients recherche un \u00e9lectrom\u00e9canicien pour son site d&#039;exploitation d&#039;Engis\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.teamone.be\/nl\/jobs\/electromecanicien-h-f-x-2\/\" \/>\n<meta property=\"og:site_name\" content=\"TeamOne\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Teamonestaffingspecialists\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.teamone.be\\\/nl\\\/jobs\\\/electromecanicien-h-f-x-2\\\/\",\"url\":\"https:\\\/\\\/www.teamone.be\\\/nl\\\/jobs\\\/electromecanicien-h-f-x-2\\\/\",\"name\":\"Electrom\u00e9canicien (H\\\/F\\\/X) - TeamOne\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.teamone.be\\\/nl\\\/#website\"},\"datePublished\":\"2026-05-13T08:27:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.teamone.be\\\/nl\\\/jobs\\\/electromecanicien-h-f-x-2\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.teamone.be\\\/nl\\\/jobs\\\/electromecanicien-h-f-x-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.teamone.be\\\/nl\\\/jobs\\\/electromecanicien-h-f-x-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.teamone.be\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Electrom\u00e9canicien (H\\\/F\\\/X)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.teamone.be\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.teamone.be\\\/nl\\\/\",\"name\":\"TeamOne\",\"description\":\"Votre partenaire n\u00b01 dans la recherche de votre candidat id\u00e9al\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.teamone.be\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.teamone.be\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.teamone.be\\\/nl\\\/#organization\",\"name\":\"TeamOne\",\"url\":\"https:\\\/\\\/www.teamone.be\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.teamone.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.teamone.be\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-team-one.svg\",\"contentUrl\":\"https:\\\/\\\/www.teamone.be\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-team-one.svg\",\"width\":200,\"height\":200,\"caption\":\"TeamOne\"},\"image\":{\"@id\":\"https:\\\/\\\/www.teamone.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Teamonestaffingspecialists\",\"https:\\\/\\\/www.instagram.com\\\/teamonestaffingbelgique\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/team-one-sa\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Electrom\u00e9canicien (H\/F\/X) - TeamOne","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.teamone.be\/nl\/jobs\/electromecanicien-h-f-x-2\/","og_locale":"nl_NL","og_type":"article","og_title":"Electrom\u00e9canicien (H\/F\/X) - TeamOne","og_description":"Notre agence TeamOne de Huy est \u00e0 la recherche pour l'un de ses clients recherche un \u00e9lectrom\u00e9canicien pour son site d'exploitation d'Engis","og_url":"https:\/\/www.teamone.be\/nl\/jobs\/electromecanicien-h-f-x-2\/","og_site_name":"TeamOne","article_publisher":"https:\/\/www.facebook.com\/Teamonestaffingspecialists","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.teamone.be\/nl\/jobs\/electromecanicien-h-f-x-2\/","url":"https:\/\/www.teamone.be\/nl\/jobs\/electromecanicien-h-f-x-2\/","name":"Electrom\u00e9canicien (H\/F\/X) - TeamOne","isPartOf":{"@id":"https:\/\/www.teamone.be\/nl\/#website"},"datePublished":"2026-05-13T08:27:59+00:00","breadcrumb":{"@id":"https:\/\/www.teamone.be\/nl\/jobs\/electromecanicien-h-f-x-2\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.teamone.be\/nl\/jobs\/electromecanicien-h-f-x-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.teamone.be\/nl\/jobs\/electromecanicien-h-f-x-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.teamone.be\/nl\/"},{"@type":"ListItem","position":2,"name":"Electrom\u00e9canicien (H\/F\/X)"}]},{"@type":"WebSite","@id":"https:\/\/www.teamone.be\/nl\/#website","url":"https:\/\/www.teamone.be\/nl\/","name":"TeamOne","description":"Votre partenaire n\u00b01 dans la recherche de votre candidat id\u00e9al","publisher":{"@id":"https:\/\/www.teamone.be\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.teamone.be\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.teamone.be\/nl\/#organization","name":"TeamOne","url":"https:\/\/www.teamone.be\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.teamone.be\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.teamone.be\/wp-content\/uploads\/2025\/05\/logo-team-one.svg","contentUrl":"https:\/\/www.teamone.be\/wp-content\/uploads\/2025\/05\/logo-team-one.svg","width":200,"height":200,"caption":"TeamOne"},"image":{"@id":"https:\/\/www.teamone.be\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Teamonestaffingspecialists","https:\/\/www.instagram.com\/teamonestaffingbelgique","https:\/\/www.linkedin.com\/company\/team-one-sa\/"]}]}},"job_city_terms":[{"id":197,"name":"Engis","slug":"engis"}],"job_sector_terms":[{"id":25,"name":"Industrie (autres)","slug":"industrie-autres"}],"job_branch_terms":[{"id":172,"name":"TeamOne Huy-Namur","slug":"team-one-huy"}],"job_province_terms":[{"id":159,"name":"Li\u00e8ge","slug":"liege"}],"job_function_terms":[{"id":87,"name":"Electricit\u00e9","slug":"electricite"}],"_links":{"self":[{"href":"https:\/\/www.teamone.be\/nl\/wp-json\/wp\/v2\/job\/1220","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.teamone.be\/nl\/wp-json\/wp\/v2\/job"}],"about":[{"href":"https:\/\/www.teamone.be\/nl\/wp-json\/wp\/v2\/types\/job"}],"wp:attachment":[{"href":"https:\/\/www.teamone.be\/nl\/wp-json\/wp\/v2\/media?parent=1220"}],"wp:term":[{"taxonomy":"job_sector","embeddable":true,"href":"https:\/\/www.teamone.be\/nl\/wp-json\/wp\/v2\/job_sector?post=1220"},{"taxonomy":"job_function","embeddable":true,"href":"https:\/\/www.teamone.be\/nl\/wp-json\/wp\/v2\/job_function?post=1220"},{"taxonomy":"job_branch","embeddable":true,"href":"https:\/\/www.teamone.be\/nl\/wp-json\/wp\/v2\/job_branch?post=1220"},{"taxonomy":"job_province","embeddable":true,"href":"https:\/\/www.teamone.be\/nl\/wp-json\/wp\/v2\/job_province?post=1220"},{"taxonomy":"job_city","embeddable":true,"href":"https:\/\/www.teamone.be\/nl\/wp-json\/wp\/v2\/job_city?post=1220"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}