{"id":1819,"date":"2026-08-31T22:02:13","date_gmt":"2026-08-31T22:02:13","guid":{"rendered":"https:\/\/www.teamone.be\/jobs\/boucher-gerant-h-f-x\/"},"modified":"2026-09-02T21:12:03","modified_gmt":"2026-09-02T21:12:03","slug":"boucher-gerant-h-f-x","status":"publish","type":"job","link":"https:\/\/www.teamone.be\/nl\/jobs\/boucher-gerant-h-f-x\/","title":{"rendered":"Boucher g\u00e9rant (H\/F\/X)"},"content":{"rendered":"<p>En tant que Boucher (H\/F\/X), vous serez en charge de la pr\u00e9paration, de la d\u00e9coupe et de la mise en valeur des produits de boucherie tout en garantissant un service de qualit\u00e9 aux clients.<\/p>\n<p>Lieu : (Bruxelles) <\/p>\n<p>Vos principales t\u00e2ches :<\/p>\n<p>&#8211; R\u00e9ceptionner et contr\u00f4ler les marchandises ;<br \/>\n&#8211; R\u00e9aliser les d\u00e9coupes de viandes selon les techniques de boucherie ;<br \/>\n&#8211; Pr\u00e9parer les produits destin\u00e9s \u00e0 la vente (d\u00e9sossage, parage, pr\u00e9paration de sp\u00e9cialit\u00e9s, etc.) ;<br \/>\n&#8211; Assurer la pr\u00e9sentation attractive du comptoir ;<br \/>\n&#8211; Conseiller et servir les clients avec professionnalisme ;<br \/>\n&#8211; Veiller au respect strict des normes d\u2019hygi\u00e8ne et de s\u00e9curit\u00e9 alimentaire ;<br \/>\n&#8211; Participer \u00e0 l\u2019entretien du mat\u00e9riel et de l\u2019espace de travail ;<br \/>\n&#8211; Travailler en collaboration avec l\u2019\u00e9quipe afin d\u2019assurer le bon fonctionnement du service.<\/p>\n<p>Ce que nous vous offrons : <\/p>\n<p>&#8211; Horaires en temps plein<br \/>\n&#8211; Contrat sous la CP 200 ;<br \/>\n&#8211; Poste de Boucher g\u00e9rant (H\/F\/X) ;<br \/>\n&#8211; Fonction vari\u00e9e avec horaires tournants et travail en \u00e9quipe ;<br \/>\n&#8211; Environnement de travail dynamique et professionnel ;<br \/>\n&#8211; Possibilit\u00e9 d\u2019\u00e9volution et de stabilit\u00e9 ;<br \/>\n&#8211; Int\u00e9gration au sein d\u2019une soci\u00e9t\u00e9 reconnue dans son secteur.<\/p>\n<p>Envoyez nous votre candidature d\u00e8s maintenant \u00e0 l&#8217;adresse hainaut@teamone.be et rejoignez une \u00e9quipe o\u00f9 votre savoir-faire sera valoris\u00e9 au quotidien.<\/p>\n<p>#TeamHainaut<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En tant que Boucher (H\/F\/X), vous serez en charge de la pr\u00e9paration, de la d\u00e9coupe et de la mise en valeur des produits de boucherie tout en garantissant un service de qualit\u00e9 aux clients. Lieu : (Bruxelles) Vos principales t\u00e2ches : &#8211; R\u00e9ceptionner et contr\u00f4ler les marchandises ; &#8211; R\u00e9aliser les d\u00e9coupes de viandes selon [&hellip;]<\/p>\n","protected":false},"template":"","job_sector":[55],"job_function":[69],"job_branch":[178],"job_province":[169],"job_city":[208],"class_list":["post-1819","job","type-job","status-publish","hentry","job_sector-alimentaire-industrie-alimentaire","job_function-alimentaire","job_branch-teamone-lalouviere","job_province-brabant-wallon","job_city-brussel-1"],"acf":{"external_id":"9414","reference":"","city":"Brussel 1","zip":"1000","duration":"int\u00e9rim en vue d'engagement","required_years_of_experience":1,"language":"Frans","sector_text":"Voeding\/voedingsindustrie","intro":"","task_and_profile":"En tant que Boucher (H\/F\/X), vous serez en charge de la pr\u00e9paration, de la d\u00e9coupe et de la mise en valeur des produits de boucherie tout en garantissant un service de qualit\u00e9 aux clients.\n\nLieu : (Bruxelles) \n\nVos principales t\u00e2ches :\n\n- R\u00e9ceptionner et contr\u00f4ler les marchandises ;\n- R\u00e9aliser les d\u00e9coupes de viandes selon les techniques de boucherie ;\n- Pr\u00e9parer les produits destin\u00e9s \u00e0 la vente (d\u00e9sossage, parage, pr\u00e9paration de sp\u00e9cialit\u00e9s, etc.) ;\n- Assurer la pr\u00e9sentation attractive du comptoir ;\n- Conseiller et servir les clients avec professionnalisme ;\n- Veiller au respect strict des normes d\u2019hygi\u00e8ne et de s\u00e9curit\u00e9 alimentaire ;\n- Participer \u00e0 l\u2019entretien du mat\u00e9riel et de l\u2019espace de travail ;\n- Travailler en collaboration avec l\u2019\u00e9quipe afin d\u2019assurer le bon fonctionnement du service.","offer":"\nCe que nous vous offrons : \n\n- Horaires en temps plein \n- Contrat sous la CP 200 ;\n- Poste de Boucher g\u00e9rant (H\/F\/X) ;\n- Fonction vari\u00e9e avec horaires tournants et travail en \u00e9quipe ;\n- Environnement de travail dynamique et professionnel ;\n- Possibilit\u00e9 d\u2019\u00e9volution et de stabilit\u00e9 ;\n- Int\u00e9gration au sein d\u2019une soci\u00e9t\u00e9 reconnue dans son secteur.\n\nEnvoyez nous votre candidature d\u00e8s maintenant \u00e0 l'adresse hainaut@teamone.be et rejoignez une \u00e9quipe o\u00f9 votre savoir-faire sera valoris\u00e9 au quotidien.\n\n#TeamHainaut","skills":"Vos comp\u00e9tences :\n\n- Vous disposez d\u2019une premi\u00e8re exp\u00e9rience en tant que boucher ;\n- Vous ma\u00eetrisez les techniques de d\u00e9coupe et de pr\u00e9paration des viandes ;\n- Vous \u00eates rigoureux(se), organis\u00e9(e) et attentif(ve) \u00e0 la qualit\u00e9 ;\n- Vous appr\u00e9ciez le travail en \u00e9quipe ;\n- Vous avez le sens du service et du contact client ;\n- Vous respectez les r\u00e8gles d\u2019hygi\u00e8ne et de s\u00e9curit\u00e9 ;\n- Vous \u00eates flexible au niveau des horaires et appr\u00e9ciez les postes vari\u00e9s.","client_name":"DUFRAIS","publication_start":"2026-09-01","publication_end":"2026-10-01"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Boucher g\u00e9rant (H\/F\/X) - TeamOne<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.teamone.be\/nl\/jobs\/boucher-gerant-h-f-x\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Boucher g\u00e9rant (H\/F\/X) - TeamOne\" \/>\n<meta property=\"og:description\" content=\"En tant que Boucher (H\/F\/X), vous serez en charge de la pr\u00e9paration, de la d\u00e9coupe et de la mise en valeur des produits de boucherie tout en garantissant un service de qualit\u00e9 aux clients. Lieu : (Bruxelles) Vos principales t\u00e2ches : &#8211; R\u00e9ceptionner et contr\u00f4ler les marchandises ; &#8211; R\u00e9aliser les d\u00e9coupes de viandes selon [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.teamone.be\/nl\/jobs\/boucher-gerant-h-f-x\/\" \/>\n<meta property=\"og:site_name\" content=\"TeamOne\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/Teamonestaffingspecialists\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-02T21:12:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.teamone.be\/wp-content\/uploads\/2026\/03\/Teamone-Groupe-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuut\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.teamone.be\\\/nl\\\/jobs\\\/boucher-gerant-h-f-x\\\/\",\"url\":\"https:\\\/\\\/www.teamone.be\\\/nl\\\/jobs\\\/boucher-gerant-h-f-x\\\/\",\"name\":\"Boucher g\u00e9rant (H\\\/F\\\/X) - TeamOne\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.teamone.be\\\/nl\\\/#website\"},\"datePublished\":\"2026-08-31T22:02:13+00:00\",\"dateModified\":\"2026-09-02T21:12:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.teamone.be\\\/nl\\\/jobs\\\/boucher-gerant-h-f-x\\\/#breadcrumb\"},\"inLanguage\":\"nl-NL\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.teamone.be\\\/nl\\\/jobs\\\/boucher-gerant-h-f-x\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.teamone.be\\\/nl\\\/jobs\\\/boucher-gerant-h-f-x\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.teamone.be\\\/nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Boucher g\u00e9rant (H\\\/F\\\/X)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.teamone.be\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.teamone.be\\\/nl\\\/\",\"name\":\"TeamOne\",\"description\":\"Votre partenaire n\u00b01 dans la recherche de votre candidat id\u00e9al\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.teamone.be\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.teamone.be\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.teamone.be\\\/nl\\\/#organization\",\"name\":\"TeamOne\",\"url\":\"https:\\\/\\\/www.teamone.be\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.teamone.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.teamone.be\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-team-one.svg\",\"contentUrl\":\"https:\\\/\\\/www.teamone.be\\\/wp-content\\\/uploads\\\/2025\\\/05\\\/logo-team-one.svg\",\"width\":200,\"height\":200,\"caption\":\"TeamOne\"},\"image\":{\"@id\":\"https:\\\/\\\/www.teamone.be\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/Teamonestaffingspecialists\",\"https:\\\/\\\/www.instagram.com\\\/teamonestaffingbelgique\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/team-one-sa\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Boucher g\u00e9rant (H\/F\/X) - TeamOne","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.teamone.be\/nl\/jobs\/boucher-gerant-h-f-x\/","og_locale":"nl_NL","og_type":"article","og_title":"Boucher g\u00e9rant (H\/F\/X) - TeamOne","og_description":"En tant que Boucher (H\/F\/X), vous serez en charge de la pr\u00e9paration, de la d\u00e9coupe et de la mise en valeur des produits de boucherie tout en garantissant un service de qualit\u00e9 aux clients. Lieu : (Bruxelles) Vos principales t\u00e2ches : &#8211; R\u00e9ceptionner et contr\u00f4ler les marchandises ; &#8211; R\u00e9aliser les d\u00e9coupes de viandes selon [&hellip;]","og_url":"https:\/\/www.teamone.be\/nl\/jobs\/boucher-gerant-h-f-x\/","og_site_name":"TeamOne","article_publisher":"https:\/\/www.facebook.com\/Teamonestaffingspecialists","article_modified_time":"2026-09-02T21:12:03+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/www.teamone.be\/wp-content\/uploads\/2026\/03\/Teamone-Groupe-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minuut"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.teamone.be\/nl\/jobs\/boucher-gerant-h-f-x\/","url":"https:\/\/www.teamone.be\/nl\/jobs\/boucher-gerant-h-f-x\/","name":"Boucher g\u00e9rant (H\/F\/X) - TeamOne","isPartOf":{"@id":"https:\/\/www.teamone.be\/nl\/#website"},"datePublished":"2026-08-31T22:02:13+00:00","dateModified":"2026-09-02T21:12:03+00:00","breadcrumb":{"@id":"https:\/\/www.teamone.be\/nl\/jobs\/boucher-gerant-h-f-x\/#breadcrumb"},"inLanguage":"nl-NL","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.teamone.be\/nl\/jobs\/boucher-gerant-h-f-x\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.teamone.be\/nl\/jobs\/boucher-gerant-h-f-x\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.teamone.be\/nl\/"},{"@type":"ListItem","position":2,"name":"Boucher g\u00e9rant (H\/F\/X)"}]},{"@type":"WebSite","@id":"https:\/\/www.teamone.be\/nl\/#website","url":"https:\/\/www.teamone.be\/nl\/","name":"TeamOne","description":"Votre partenaire n\u00b01 dans la recherche de votre candidat id\u00e9al","publisher":{"@id":"https:\/\/www.teamone.be\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.teamone.be\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.teamone.be\/nl\/#organization","name":"TeamOne","url":"https:\/\/www.teamone.be\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.teamone.be\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.teamone.be\/wp-content\/uploads\/2025\/05\/logo-team-one.svg","contentUrl":"https:\/\/www.teamone.be\/wp-content\/uploads\/2025\/05\/logo-team-one.svg","width":200,"height":200,"caption":"TeamOne"},"image":{"@id":"https:\/\/www.teamone.be\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/Teamonestaffingspecialists","https:\/\/www.instagram.com\/teamonestaffingbelgique","https:\/\/www.linkedin.com\/company\/team-one-sa\/"]}]}},"job_city_terms":[{"id":208,"name":"Brussel 1","slug":"brussel-1"}],"job_sector_terms":[{"id":55,"name":"Alimentaire\/ Industrie alimentaire","slug":"alimentaire-industrie-alimentaire"}],"job_branch_terms":[{"id":178,"name":"TeamOne Hainaut","slug":"teamone-lalouviere"}],"job_province_terms":[{"id":169,"name":"Brabant wallon","slug":"brabant-wallon"}],"job_function_terms":[{"id":69,"name":"Alimentaire","slug":"alimentaire"}],"_links":{"self":[{"href":"https:\/\/www.teamone.be\/nl\/wp-json\/wp\/v2\/job\/1819","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.teamone.be\/nl\/wp-json\/wp\/v2\/job"}],"about":[{"href":"https:\/\/www.teamone.be\/nl\/wp-json\/wp\/v2\/types\/job"}],"wp:attachment":[{"href":"https:\/\/www.teamone.be\/nl\/wp-json\/wp\/v2\/media?parent=1819"}],"wp:term":[{"taxonomy":"job_sector","embeddable":true,"href":"https:\/\/www.teamone.be\/nl\/wp-json\/wp\/v2\/job_sector?post=1819"},{"taxonomy":"job_function","embeddable":true,"href":"https:\/\/www.teamone.be\/nl\/wp-json\/wp\/v2\/job_function?post=1819"},{"taxonomy":"job_branch","embeddable":true,"href":"https:\/\/www.teamone.be\/nl\/wp-json\/wp\/v2\/job_branch?post=1819"},{"taxonomy":"job_province","embeddable":true,"href":"https:\/\/www.teamone.be\/nl\/wp-json\/wp\/v2\/job_province?post=1819"},{"taxonomy":"job_city","embeddable":true,"href":"https:\/\/www.teamone.be\/nl\/wp-json\/wp\/v2\/job_city?post=1819"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}